{"id":31163,"date":"2023-11-27T13:45:32","date_gmt":"2023-11-27T13:45:32","guid":{"rendered":"https:\/\/blog.medel.pro\/flex-cochlear-implant-electrode-arrays\/"},"modified":"2023-11-27T18:45:55","modified_gmt":"2023-11-27T18:45:55","slug":"flex-cochlear-implant-electrode-arrays","status":"publish","type":"post","link":"https:\/\/blog.medel.pro\/latam\/quirurgico\/flex-cochlear-implant-electrode-arrays\/","title":{"rendered":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Al momento de elegir una gu\u00eda de electrodos para un implante coclear, la atraumaticidad siempre deber\u00eda ser una prioridad. Incluso para los candidatos que no tienen audici\u00f3n residual, las estructuras cocleares intactas son un factor importante para la capacidad auditiva.<\/p>\n<p>El da\u00f1o a la c\u00f3clea durante la inserci\u00f3n puede afectar significativamente el resultado de la audici\u00f3n. Una desviaci\u00f3n de la gu\u00eda de electrodos dentro de la rampa vestibular puede causar p\u00e9rdida de la funci\u00f3n auditiva natural, da\u00f1o en las estructuras neuronales, confusi\u00f3n de tonos, y calificaciones de percepci\u00f3n del habla significativamente m\u00e1s bajas. 1,2,3,4,5,6<\/p>\n<p>La c\u00f3clea es un \u00f3rgano incre\u00edblemente delicado, lo que significa que las gu\u00edas de electrodos atraum\u00e1ticas son una consideraci\u00f3n esencial para cualquier paciente. Durante 30 a\u00f1os hemos trabajados para crear la gu\u00eda de electrodos para implantes cocleares m\u00e1s atraum\u00e1tica posible. 1<\/p>\n<p>Hoy vamos a ver c\u00f3mo nuestra serie de gu\u00edas de electrodos FLEX ofrece una flexibilidad incomparable y una atraumaticidad que ninguna otra gu\u00eda de electrodos puede igualar. 1,4,5,6<\/p>\n<p>&nbsp;<\/p>\n<h3>Gu\u00edas de electrodos FLEX<\/h3>\n<p>Primero, veamos c\u00f3mo es el dise\u00f1o general de las gu\u00edas FLEX. La serie FLEX son gu\u00edas de pared lateral de ajuste libre que pueden adaptarse libremente a la forma y curvatura de cada c\u00f3clea \u00fanica. Esta versatilidad de ajuste libre hace que las matrices FLEX sean una excelente opci\u00f3n para casi cualquier candidato a implante coclear.<\/p>\n<p>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29733 size-full\" src=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English.jpg\" alt=\"Our FLEX electrode arrays offer unparalleled flexibility and atraumaticity that no other cochlear implant electrode arrays can match.\" width=\"800\" height=\"1023\" srcset=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English.jpg 800w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-235x300.jpg 235w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-768x982.jpg 768w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-516x660.jpg 516w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-480x614.jpg 480w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-595x761.jpg 595w, https:\/\/blog.medel.pro\/wp-content\/uploads\/2017\/11\/MED-EL-Electrodes-FLEX_English-500x639.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Actualmente, hay 6 electrodos en la serie FLEX:<\/p>\n<ul>\n<li>FLEX 34: Una gu\u00eda de electrodos de 34 mm dise\u00f1ada para cubrir completamente la c\u00f3clea; la gu\u00eda FLEX m\u00e1s larga.<\/li>\n<li>FLEXSOFT: Una gu\u00eda de electrodos de 31,5 mm dise\u00f1ada para cubrir completamente la c\u00f3clea<\/li>\n<li>FLEX28: Una gu\u00eda de electrodos de 28 mm dise\u00f1ada para cubrir la totalidad de la c\u00f3clea; adecuada para el 96% de las anatom\u00edas cocleares normales. 7,8<\/li>\n<li>FLEX26: Una gu\u00eda de electrodos de 26 mm dise\u00f1ada para cubrir completamente la c\u00f3clea<\/li>\n<li>FLEX 24: Una gu\u00eda de electrodos de 24 mm tambi\u00e9n dise\u00f1ada para la Estimulaci\u00f3n electroac\u00fastica (EAS)<\/li>\n<li>FLEX 20: Una gu\u00eda de electrodos de 20 mm dise\u00f1ada para EAS o para otras necesidades espec\u00edficas.<\/li>\n<\/ul>\n<p>Hay 5 factores de dise\u00f1o claves que hacen que las gu\u00edas de electrodos FLEX sean las m\u00e1s atraum\u00e1ticas disponibles en el mercado.<\/p>\n<ul>\n<li>Gu\u00eda de pared lateral<\/li>\n<li>Optimizada para inserci\u00f3n por ventana redonda<\/li>\n<li>Cables con forma de onda<\/li>\n<li>\u00d3ptimo espacio de contactos<\/li>\n<li>Tecnolog\u00eda FLEX-Tip<\/li>\n<\/ul>\n<p>Ninguna otra gu\u00eda disponible en el mercado ofrece esta combinaci\u00f3n. Veamos por qu\u00e9 cada factor es tan importante para la flexibilidad y atraumaticidad general.<strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3>Gu\u00eda de electrodos de pared lateral<\/h3>\n<p>Siempre hemos usado gu\u00edas de electrodos de pared lateral porque son un factor clave para la atraumaticidad. Varios estudios recientes han hallado que la desviaci\u00f3n escalar de la gu\u00eda de electrodos es mucho m\u00e1s probable con gu\u00edas de electrodos perimodiolares o de escala media.<sup>1,5,6,9<\/sup><\/p>\n<p>Las gu\u00edas precurvadas perimodiolares o de escala media est\u00e1n dise\u00f1adas para curvarse hacia adentro, lo cual puede da\u00f1ar estructuras delicadas de la c\u00f3clea. Estas gu\u00edas de electrodos perimodiolares de tama\u00f1o \u00fanico no est\u00e1n dise\u00f1adas para adaptarse a cada c\u00f3clea espec\u00edfica.<strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3>Inserci\u00f3n por ventana redonda<\/h3>\n<p>El abordaje quir\u00fargico tambi\u00e9n es un factor importante en la preservaci\u00f3n de la audici\u00f3n. Una cocleostom\u00eda puede derivar en una mayor probabilidad de colocar los electrodos en la rampa vestibular. La t\u00e9cnica de la ventana redonda ha demostrado mejores pron\u00f3sticos de colocar los electrodos completamente en la rampa timp\u00e1nica.<sup>5,6,10\u00a0<\/sup><\/p>\n<p>La inserci\u00f3n por ventana redonda tiene beneficios m\u00e1s all\u00e1 de la colocaci\u00f3n escalar. Adem\u00e1s de una colocaci\u00f3n m\u00e1s consistente, la inserci\u00f3n por ventana redonda est\u00e1 muy asociada a la ausencia de hidropes\u00eda y fibrosis del o\u00eddo interno en comparaci\u00f3n con la cocleostom\u00eda. La cocleostom\u00eda tambi\u00e9n puede causar m\u00e1s trauma ac\u00fastico por la perforaci\u00f3n.<sup>17,18<\/sup><\/p>\n<p>Nuestras gu\u00edas de electrodos FLEX est\u00e1n dise\u00f1adas para inserci\u00f3n por ventana redonda. En el FLEX28, FLEX26, el FLEX24, y el FLEX20, el di\u00e1metro de base del electrodo es de solo 0,8 mm, lo que permite una inserci\u00f3n atraum\u00e1tica sin necesidad de perforar.<\/p>\n<p>Por supuesto, estos electrodos tambi\u00e9n se pueden insertar utilizando una cocleostom\u00eda tradicional o un abordaje de ventana redonda extendido. La flexibilidad quir\u00fargica es importante, ya que la anatom\u00eda de cada paciente es \u00fanica.<\/p>\n<h3><\/h3>\n<h3>Cables con forma de onda<\/h3>\n<p>Todas las gu\u00edas MED-EL usan nuestros exclusivos cables con forma de onda de platino-iridio. \u00bfPor qu\u00e9 son tan importantes los cables con forma de onda? Las ondas les permiten a los cables doblarse con mucha m\u00e1s facilidad, lo que reduce significativamente la rigidez en comparaci\u00f3n con el dise\u00f1o de cables rectos.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6139\" src=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2019\/11\/wave-shaped-wires.jpg\" alt=\"\" width=\"800\" height=\"255\" \/><\/p>\n<p>Esto reduce la fuerza de inserci\u00f3n y ayuda a minimizar el riesgo de desviarse dentro de la rampa vestibular o de da\u00f1ar otra estructura de la c\u00f3clea.<\/p>\n<p>&nbsp;<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6140\" src=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2019\/11\/wave-shaped-wires-graph.jpg\" alt=\"\" width=\"402\" height=\"300\" \/><\/em><\/p>\n<p><em>Cables en forma de onda (l\u00ednea s\u00f3lida) contra cables rectos (l\u00ednea punteada)<\/em><\/p>\n<p><em>Los cables con forma de onda est\u00e1n dise\u00f1ados para reducir la fuerza de inserci\u00f3n de la gu\u00eda de electrodos, en comparaci\u00f3n con los cables rectos. Esta aproximaci\u00f3n muestra c\u00f3mo el dise\u00f1o del cable puede afectar potencialmente las fuerzas de inserci\u00f3n.<\/em><\/p>\n<h3>\u00d3ptimo espacio de contactos<\/h3>\n<p>Para conseguir una flexibilidad y calidad de sonido superior, nuestras gu\u00edas de electrodos utilizan 12 canales espaciados uniformemente a lo largo de una larga gu\u00eda de electrodos. Esto minimiza la interacci\u00f3n entre canales y mejora la flexibilidad mec\u00e1nica.<\/p>\n<p>Las gu\u00edas de electrodos de otros fabricantes utilizan gu\u00edas cortas que comprimen densamente los contactos de los electrodos. Esto reduce la flexibilidad y no ofrece una correspondencia natural entre tono y lugar a lo largo de toda la c\u00f3clea.<sup>11,14<\/sup><\/p>\n<p>Como hemos visto anteriormente, las consideraciones m\u00e1s importantes para la calidad del sonido son lograr una cobertura coclear completa y proporcionar\u00a0una codificaci\u00f3n precisa del sonido. Si los contactos de los electrodos est\u00e1n muy cerca unos de otros, hay posibilidades de que dos contactos adyacentes estimulen el mismo conjunto de fibras nerviosas en la c\u00f3clea.<\/p>\n<p>&nbsp;<\/p>\n<h3>Tecnolog\u00eda FLEX-Tip<\/h3>\n<p>Todas las gu\u00edas de electrodos de MED-EL utilizan dise\u00f1o de pared lateral, espaciado de contactos optimizado y cables con forma de onda. Esto es lo que hace que las gu\u00edas de electros MED-EL sean una opci\u00f3n excelente para las cirug\u00edas atraum\u00e1ticas.<\/p>\n<p>Entonces, \u00bfqu\u00e9 es lo que hace que las gu\u00edas FLEX sean las m\u00e1s atraum\u00e1ticas del mercado? Ah\u00ed es donde entra en juego la tecnolog\u00eda FLEX-Tip. Nuestras gu\u00edas FLEX tienen una un extremo FLEX-Tip, que utiliza contactos simples en cada extremo. Nuestras otras gu\u00edas de electrodos utilizan 12 contactos de electros en pares a lo largo de toda la gu\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6141\" src=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2019\/11\/flex-tip-technology.jpg\" alt=\"\" width=\"649\" height=\"373\" \/><\/p>\n<p>Los primeros 5 contactos apicales son contactos simples, y el resto de la gu\u00eda FLEX utiliza contactos en pares. Al utilizar contactos simples, el extremo FLEX-Tip de la gu\u00eda es m\u00e1s flexible y puede estrecharse hasta 0,5 x 0,4 mm (FLEX28). Esto hace que FLEX-Tip sea excepcionalmente flexible y atraum\u00e1tica.<\/p>\n<p>A diferencia de las gu\u00edas perimodiolares o de escala media, FLEX-Tip est\u00e1 suavemente redondeada para evitar atascarse en estructuras intracocleares.\u00a0El extremo flexible se desliza delicadamente a lo largo de la rampa timp\u00e1nica, evitando da\u00f1ar la membrana basilar y otras delicadas estructuras de la c\u00f3clea. Esto hace que las gu\u00edas de electrodos FLEX sean una alternativa excelente para las cirug\u00edas de preservaci\u00f3n de la audici\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<h3>Implantaci\u00f3n coclear atraum\u00e1tica<\/h3>\n<p>Al combinar los beneficios comprobados de las gu\u00edas de pared lateral, la inserci\u00f3n por ventana redonda, los cables con forma de onda, el espacio de contactos optimizado y la tecnolog\u00eda FLEX-Tip, la serie FLEX ofrece las gu\u00edas de electrodos para implantes cocleares m\u00e1s flexibles y atraum\u00e1ticas disponibles en el mercado. Ninguna otra gu\u00eda de electrodos puede igualar estos elementos de dise\u00f1o claves.<\/p>\n<p>\u00bfY los\u00a0beneficios de la inserci\u00f3n de electrodos atraum\u00e1ticos y de preservaci\u00f3n de estructuras\u00a0para sus pacientes?<\/p>\n<ul>\n<li>Mapeo de electrodos preciso <sup>1,2<\/sup><\/li>\n<li>Comprensi\u00f3n del habla significativamente mejor\u00a0<sup>4,5<\/sup><\/li>\n<li>Potencial para la preservaci\u00f3n de la audici\u00f3n<sup> 10<\/sup><\/li>\n<li>Potencial para mantener intacta la c\u00f3clea para futuras terapias<\/li>\n<\/ul>\n<p>Y con los electrodos atraum\u00e1ticos FLEX, puede\u00a0insertar profundamente las gu\u00edas de electrodos\u00a0con seguridad. \u00bfCu\u00e1les son los beneficios de poder insertar de manera segura gu\u00edas de electrodos largas?<\/p>\n<ul>\n<li>\u201cVoces mucho m\u00e1s claras y resonantes\u201d y \u201cSonido m\u00e1s profundo, resonante y natural\u201d\u00a0<sup>11<\/sup><\/li>\n<li>Entender el habla significativamente mejor en silencio y con ruido\u00a0<sup>12,13<\/sup><\/li>\n<li>Mapeo de frecuencia m\u00e1s natural\u00a0<sup>14,15<\/sup><\/li>\n<li>Comprensi\u00f3n del habla significativamente mejor en un plazo reducido\u00a0<sup>12,16<\/sup><\/li>\n<\/ul>\n<p>Con un dise\u00f1o vers\u00e1til y resultados auditivos excepcionales, las gu\u00edas FLEX son la elecci\u00f3n ideal para pr\u00e1cticamente todos los candidatos a implantes cocleares.<\/p>\n<p>&nbsp;<\/p>\n<h3>P\u00f3ngase en contacto<\/h3>\n<p>\u00bfDesea aprender m\u00e1s sobre de las t\u00e9cnicas quir\u00fargicas de preservaci\u00f3n de estructuras con gu\u00edas FLEX? Mire este <a href=\"https:\/\/blog.medel.pro\/pin-cochlear-implant-case-study\/\">estudio de caso quir\u00fargico en video de alta definici\u00f3n<\/a>\u00a0del Prof. Dr. Paul Van de Heyning.<\/p>\n<p>\u00bfTiene alguna pregunta respecto de las t\u00e9cnicas de preservaci\u00f3n con los implantes cocleares?\u00a0<a href=\"https:\/\/www.medel.pro\/contact-med-el\">\u00a1Cont\u00e1ctenos!<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em>* No todos los productos, indicaciones y caracter\u00edsticas exhibidos est\u00e1n disponibles en todos los pa\u00edses. Por favor, contacte a su representante local de MED-EL para obtener m\u00e1s informaci\u00f3n.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt;\"><em>Referencias<\/em><\/span><\/p>\n<ol>\n<li><span style=\"font-size: 10pt;\"><em>O\u2019Connell, B.P., Hunter, J.B., &amp; Wanna, G.B., (2016). The importance of electrode location in cochlear implantation. Laryngoscope Investigative Otolaryngology, 1: 169\u2013174.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Holden, L.K, Finley, C.C., Firszt, J.B., Holden, T.A., Brenner, C, Potts, L.G., Gotter, B.D., Vanderhoof, S.S., Mispagel, K., Heydebrand, G., &amp; Skinner, M.W. (2013) Factors affecting open-set word recognition in adults with cochlear implants. Ear Hear. 34(3):342\u2013360.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Nin, F., Hibino, H., Doi, K., Suzuki, T., Hisa, Y., &amp; Kurachi, Y. (2008) The endocochlear potential depends on two K+ diffusion potentials and an electrical barrier in the stria vascularis of the inner ear. Proc Natl Acad Sci USA. 105(5):1751\u20131756.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Wanna, G.B., Noble, J.H., Gifford, R.H., Dietrich, M.S., Sweeney, A.D., Zhang, D., Dawant, B.M., Rivas, A., &amp; Labadie, R.F. (2015) Impact of intrascalar electrode location, electrode type, and angular insertion depth on residual hearing in cochlear implant patients: Preliminary results. Otol Neurotol. 36(8):1343\u20131348.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Wanna, G.B., Noble, J.H., Carlson, M.L., Gifford, R.H., Dietrich, M.S., Haynes, D.S., Dawant, B.M., &amp; Labadie, R.F. (2014) Impact of electrode design and surgical approach on scalar location and cochlear implant outcomes. Laryngoscope. 124(6):1\u20137.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>O\u2019Connell, B.P., Cakir, A., Hunter, J.B., Francis, D.O., Noble, J.H., Labadie, R.F., Zuniga, G., Dawant, B.M., Rivas, A., &amp; Wanna, G.B. (2016) Electrode location and angular insertion depth are predictors of audiologic outcomes in cochlear implantation. Otol Neurotol. 37(8):1016\u20131023.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Hardy, M. (1938). The length of the organ of Corti in man. J. Anat., 62, 291\u2013311.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Ni, Y. Dai, P., Dai, C., &amp; Li, H.. (2017) Cochlear implant-related three-dimensional characteristics determined by micro-computed tomography reconstruction. Clin Anat., 30(1), 39\u201343.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Boyer, E., Karkas, A., Attye, A., Lefournier, V., Escude, B., &amp; Schmerber, S. (2015) Scalar localization by cone-beam computed tomography of cochlear implant carriers: A comparative study between straight and periomodiolar precurved electrode arrays. Otol Neurotol. 36(3):422\u2013429.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Nordfalk, K., Rasmussen, K., Hopp, E., Bunne, M., Silvola, J.T., &amp; Jablonski, G.E., (2016). Insertion Depth in Cochlear Implantation and Outcome in Residual Hearing and Vestibular Function. Ear Hear. 37(2):e129\u2013137.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Harris, R.L., Gibson, W.P. Johnson, M., Brew, J., Bray, M., &amp; Psarros, C. (2011) Intra-individual assessment of speech and music perception in cochlear implant users with contralateral Cochlear and MED-EL systems. Acta Otolaryngol., 131(12), 1270\u20131278.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Buchman, C.A., Dillon, M.T., King, E.R., Adunka, M.C., Adunka, O.F., &amp; Pillsbury, H.C. (2014). Influence of cochlear implant insertion depth on performance: a prospective randomized trial. Otol Neurotol., 35(10), 1773\u20131779.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>O\u2019Connell, B.P., Hunter, J.B., Haynes, D.S., Holder, J.T., Dedmon, M.M., Noble, J.H., Dawant, B.M., &amp; Wanna, G.B. (2017) Insertion depth impacts speech perception and hearing preservation for lateral wall electrodes. Laryngoscope. Epub ahead of print.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Rader, T., D\u00f6ge, J., Adel, Y., Weissgerber, T., &amp; Baumann, U. (2016). Place dependent stimulation rates improve pitch perception in cochlear implantees with single-sided deafness. Hear Res., 339, 94\u2013103.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Vermeire, K., Landsberger, D.M., Van de Heyning, P.H., Voormolen, M., Kleine Punte, A., Schatzer, R., &amp; Zierhofer, C. (2015) Frequency-place map for electrical stimulation in cochlear implants: Change over time. Hear Res., 326,8\u201314.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Helbig, S., Helbig, M., Leinung, M., St\u00f6ver, T., Baumann, U., &amp; Rader, T. (2015). Hearing preservation and improved speech perception with a flexible 28-mm electrode. Otol Neurotol. 36(1):34-42.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Ishiyama, A., Doherty, J., Ishiyama, G., Quesnel, A.M., Lopez, I., &amp; Linthicum, F.H. (2016). Post Hybrid Cochlear Implant Hearing Loss and Endolymphatic Hydrops. Otol Neurotol. 37(10):1516\u20131521.<\/em><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><em>Causon, A. Verschuur, C., &amp; Newman, T.A. (2015) A retrospective Analysis of the contribution of reported factors in cochlear implantation on hearing preservation outcomes. Otol Neurotol. 36 (7) 1137\u20131145<\/em><\/span><\/li>\n<\/ol>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Al momento de elegir una gu\u00eda de electrodos para un implante coclear, la atraumaticidad siempre deber\u00eda ser una prioridad. Incluso para los candidatos que no tienen audici\u00f3n residual, las estructuras cocleares intactas son un factor importante para la capacidad auditiva. El da\u00f1o a la c\u00f3clea durante la inserci\u00f3n puede afectar significativamente el resultado de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2552],"tags":[],"class_list":["post-31163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quirurgico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog<\/title>\n<meta name=\"description\" content=\"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog\" \/>\n<meta property=\"og:description\" content=\"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\" \/>\n<meta property=\"og:site_name\" content=\"MED-EL Professionals Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T13:45:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T18:45:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@medel\" \/>\n<meta name=\"twitter:site\" content=\"@medel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\/\/blog.medel.pro\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02\"},\"headline\":\"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas\",\"datePublished\":\"2023-11-27T13:45:32+00:00\",\"dateModified\":\"2023-11-27T18:45:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\"},\"wordCount\":2261,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png\",\"articleSection\":[\"Quir\u00fargico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\",\"url\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\",\"name\":\"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.medel.pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png\",\"datePublished\":\"2023-11-27T13:45:32+00:00\",\"dateModified\":\"2023-11-27T18:45:55+00:00\",\"description\":\"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png\",\"width\":800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.medel.pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.medel.pro\/#website\",\"url\":\"https:\/\/blog.medel.pro\/\",\"name\":\"MED-EL Professionals Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.medel.pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.medel.pro\/#organization\",\"name\":\"MED-EL Professionals Blog\",\"url\":\"https:\/\/blog.medel.pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.medel.pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"width\":200,\"height\":200,\"caption\":\"MED-EL Professionals Blog\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/medel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.medel.pro\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02\",\"name\":\"MED-EL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog","description":"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/","og_locale":"es_ES","og_type":"article","og_title":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog","og_description":"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.","og_url":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/","og_site_name":"MED-EL Professionals Blog","article_published_time":"2023-11-27T13:45:32+00:00","article_modified_time":"2023-11-27T18:45:55+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png","type":"image\/png"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_creator":"@medel","twitter_site":"@medel","twitter_misc":{"Written by":"MED-EL","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#article","isPartOf":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.pro\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02"},"headline":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas","datePublished":"2023-11-27T13:45:32+00:00","dateModified":"2023-11-27T18:45:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/"},"wordCount":2261,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.pro\/#organization"},"image":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png","articleSection":["Quir\u00fargico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/","url":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/","name":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas - MED-EL Professionals Blog","isPartOf":{"@id":"https:\/\/blog.medel.pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png","datePublished":"2023-11-27T13:45:32+00:00","dateModified":"2023-11-27T18:45:55+00:00","description":"Find out the 5 key factors that make FLEX electrode arrays the most flexible and atraumatic cochlear implant electrode arrays available.","breadcrumb":{"@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#primaryimage","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/11\/para-blog-electrodos1.png","width":800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.pro\/products-updates\/flex-cochlear-implant-electrode-arrays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.pro\/"},{"@type":"ListItem","position":2,"name":"Serie FLEX: Las gu\u00edas de Electrodos para Implante Coclear m\u00e1s Atraum\u00e1ticas"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.pro\/#website","url":"https:\/\/blog.medel.pro\/","name":"MED-EL Professionals Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.pro\/#organization","name":"MED-EL Professionals Blog","url":"https:\/\/blog.medel.pro\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.pro\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","width":200,"height":200,"caption":"MED-EL Professionals Blog"},"image":{"@id":"https:\/\/blog.medel.pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/medel"]},{"@type":"Person","@id":"https:\/\/blog.medel.pro\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02","name":"MED-EL"}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/posts\/31163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/comments?post=31163"}],"version-history":[{"count":6,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/posts\/31163\/revisions"}],"predecessor-version":[{"id":31206,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/posts\/31163\/revisions\/31206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/media\/31212"}],"wp:attachment":[{"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/media?parent=31163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/categories?post=31163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.pro\/latam\/wp-json\/wp\/v2\/tags?post=31163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}