{"id":32690,"date":"2024-07-31T17:29:30","date_gmt":"2024-07-31T17:29:30","guid":{"rendered":"https:\/\/blog.medel.pro\/?p=32690"},"modified":"2024-07-31T18:54:57","modified_gmt":"2024-07-31T18:54:57","slug":"med-el-proud-platinum-sponsor-at-the-acia-conference","status":"publish","type":"post","link":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/","title":{"rendered":"MED-EL: Proud Platinum Sponsor at the ACIA Conference"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":43,"featured_media":32717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2773],"tags":[],"class_list":["post-32690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-education"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"MED-EL Professionals Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-31T17:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T18:54:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image-1024x554.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@medel\" \/>\n<meta name=\"twitter:site\" content=\"@medel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\"},\"author\":{\"name\":\"\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/d5b95460b28eb01bc3a24902f07d6996\"},\"headline\":\"MED-EL: Proud Platinum Sponsor at the ACIA Conference\",\"datePublished\":\"2024-07-31T17:29:30+00:00\",\"dateModified\":\"2024-07-31T18:54:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png\",\"articleSection\":[\"Events &amp; Education\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\",\"url\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\",\"name\":\"MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png\",\"datePublished\":\"2024-07-31T17:29:30+00:00\",\"dateModified\":\"2024-07-31T18:54:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png\",\"width\":2560,\"height\":1385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.medel.pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MED-EL: Proud Platinum Sponsor at the ACIA Conference\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#website\",\"url\":\"https:\/\/blog.medel.pro\/de\/\",\"name\":\"MED-EL Professionals Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.medel.pro\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\",\"name\":\"MED-EL Professionals Blog\",\"url\":\"https:\/\/blog.medel.pro\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"width\":200,\"height\":200,\"caption\":\"MED-EL Professionals Blog\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/medel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/d5b95460b28eb01bc3a24902f07d6996\",\"name\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/","og_locale":"en_US","og_type":"article","og_title":"MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog","og_url":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/","og_site_name":"MED-EL Professionals Blog","article_published_time":"2024-07-31T17:29:30+00:00","article_modified_time":"2024-07-31T18:54:57+00:00","og_image":[{"width":1024,"height":554,"url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image-1024x554.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@medel","twitter_site":"@medel","twitter_misc":{"Written by":"","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#article","isPartOf":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/"},"author":{"name":"","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/d5b95460b28eb01bc3a24902f07d6996"},"headline":"MED-EL: Proud Platinum Sponsor at the ACIA Conference","datePublished":"2024-07-31T17:29:30+00:00","dateModified":"2024-07-31T18:54:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.pro\/de\/#organization"},"image":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png","articleSection":["Events &amp; Education"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/","url":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/","name":"MED-EL: Proud Platinum Sponsor at the ACIA Conference - MED-EL Professionals Blog","isPartOf":{"@id":"https:\/\/blog.medel.pro\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png","datePublished":"2024-07-31T17:29:30+00:00","dateModified":"2024-07-31T18:54:57+00:00","breadcrumb":{"@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#primaryimage","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2024\/07\/ACIA-Banner-Image.png","width":2560,"height":1385},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.pro\/en-us\/events-education\/med-el-proud-platinum-sponsor-at-the-acia-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.pro\/"},{"@type":"ListItem","position":2,"name":"MED-EL: Proud Platinum Sponsor at the ACIA Conference"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.pro\/de\/#website","url":"https:\/\/blog.medel.pro\/de\/","name":"MED-EL Professionals Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.pro\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.pro\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.medel.pro\/de\/#organization","name":"MED-EL Professionals Blog","url":"https:\/\/blog.medel.pro\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","width":200,"height":200,"caption":"MED-EL Professionals Blog"},"image":{"@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/medel"]},{"@type":"Person","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/d5b95460b28eb01bc3a24902f07d6996","name":""}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/posts\/32690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/comments?post=32690"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/posts\/32690\/revisions"}],"predecessor-version":[{"id":32691,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/posts\/32690\/revisions\/32691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/media\/32717"}],"wp:attachment":[{"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/media?parent=32690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/categories?post=32690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.pro\/en-us\/wp-json\/wp\/v2\/tags?post=32690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}