{"id":25723,"date":"2023-02-23T12:57:25","date_gmt":"2023-02-23T12:57:25","guid":{"rendered":"https:\/\/blog.medel.pro\/plattformen-und-materialien-fuer-fachleute\/"},"modified":"2024-01-23T16:25:49","modified_gmt":"2024-01-23T16:25:49","slug":"plattformen-und-materialien-fuer-fachleute","status":"publish","type":"post","link":"https:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/","title":{"rendered":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden"},"content":{"rendered":"<p>Blogs, Video-Bibliotheken, Online-Seminare, Podcasts: Das MED-EL Universum bietet etliche <strong>Plattformen<\/strong> mit wertvollen Informationen, Downloads und Materialien <strong>f\u00fcr Fachleute<\/strong> \u2013 ganz egal, ob Sie in der HNO-Chirurgie, in der Audiologie oder in der Rehabilitation arbeiten.<\/p>\n<p>Bei diesem vielf\u00e4ltigen Angebot kann man aber schon einmal den \u00dcberblick verlieren. Damit Sie auch wirklich das finden, was f\u00fcr Sie von Interesse und beruflicher Relevanz ist, m\u00f6chten wir Ihnen heute einen kurzen Wegweiser durch unterschiedliche kostenlose Plattformen und Ressourcensammlungen von MED-EL liefern. Kommen Sie mit, bleiben Sie informiert \u2013 es lohnt sich!<\/p>\n<p>Um welche Online-Plattformen geht es?<\/p>\n<ul>\n<li><strong>myMedel<\/strong> \u2013 Ihr pers\u00f6nlicher all-in-one Online-Account<\/li>\n<li><strong>MED-EL Akademie<\/strong> \u2013 spannende Webinare<\/li>\n<li><strong>Surgical Video Library<\/strong> \u2013 hochaufl\u00f6sende Operationsvideos<\/li>\n<li><strong>SurgeryONLINE<\/strong> und <strong>ExpertsONLINE <\/strong>\u2013 Expertenvortr\u00e4ge mit Live-Diskussion<\/li>\n<li><strong>YouTube Professionals Channel \u2013 <\/strong>Key-Feature-Videos und archivierte Vortr\u00e4ge<\/li>\n<li><strong>MED-EL Podcasts<\/strong> \u2013 Neues aus Wissenschaft und Praxis zum Anh\u00f6ren<\/li>\n<li><strong>medel.pro<\/strong> \u2013 Produktinfos, Indikationskriterien, Downloads und Veranstaltungshinweise<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>myMED-EL<\/strong><\/h3>\n<p><u><a href=\"https:\/\/my.medel.com\/de\/register\/professional\" target=\"_blank\" rel=\"noopener\">Holen Sie sich jetzt Ihren kostenlosen myMED-EL Zugang<\/a><\/u>. myMED-EL ist Ihr pers\u00f6nliches Portal zu einer Vielzahl weiterer Plattformen und Materialien. Via myMED-EL gelangen Sie u. a. in die <strong>MED-EL Akademie<\/strong> sowie in die <strong>chirurgische Video-Bibliothek<\/strong>. Dar\u00fcber hinaus bietet myMED-EL ein umfassendes Download Center, in dem Sie Gebrauchsanweisungen nach Produkt und Land filtern und herunterladen k\u00f6nnen. Das \u201eProcessor Configuration Backup\u201c erm\u00f6glicht Audiolog*innen, individuelle H\u00f6rprogramme ihrer Patient*innen sicher in der MED-EL Cloud abzulegen und jederzeit darauf zuzugreifen.<\/p>\n<div style=\"background-color: #f0f0f0; padding: 10px 15px; border: 1px solid #ccc; float: left;\"><em><a href=\"https:\/\/my.medel.com\/de\/register\/professional\" target=\"_blank\" rel=\"noopener\">&gt;&gt; myMED-EL Konto holen<\/a><\/em><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>MED-EL Akademie<\/strong><\/h3>\n<p>\u00dcber Ihr myMED-EL Konto haben Sie vollen Zugriff auf s\u00e4mtliche Webinare in der <u><a href=\"https:\/\/academy.medel.com\/login\/index.php\" target=\"_blank\" rel=\"noopener\">MED-EL Akademie<\/a><\/u>. St\u00f6bern Sie im umfangreichen Archiv unserer Online-Seminare. Bilden Sie sich weiter, wann und wo Sie m\u00f6chten. Die gro\u00dfe Auswahl an Seminaren in unterschiedlichen Sprachen, Ihr eigenes Dashboard mit Ihren laufenden und abgeschlossenen Kursen sowie Empfehlungen speziell f\u00fcr Sie sorgen f\u00fcr maximale Flexibilit\u00e4t.<\/p>\n<h3><strong>Chirurgische Video-Bibliothek<\/strong><\/h3>\n<p>In der <u><a href=\"https:\/\/surgical-videos.medel.com\/login\/\" target=\"_blank\" rel=\"noopener\">chirurgischen Video-Bibliothek<\/a><\/u> (<em>MED-EL Surgical Video Library<\/em>) erwartet Sie eine einzigartige Sammlung hochaufl\u00f6sender kommentierter OP-Videos von Implantationen aus der ganzen Welt. Die Palette an implantierten Produkten umfasst Cochlea-Implantate ebenso wie Mittelohr- und Knochenleitungsimplantate und sogar Hirnstammimplantate.<\/p>\n<p>Erfahren Sie Interessantes zum Hintergrund der jeweiligen Patient*innen und schauen Sie erfahren Operateur*innen \u00fcber die Schulter. Die Videos sind in einzelne Kapitel gegliedert, die den jeweiligen chirurgischen Schritten chronologisch folgen. Und dank der herausragenden ARRI Bildqualit\u00e4t wird jedes noch so kleine Detail in unvergleichlicher Sch\u00e4rfe dargestellt.<\/p>\n<h3><strong>SurgeryONLINE<\/strong> und <strong>ExpertsONLINE <\/strong><\/h3>\n<p>Mit ExpertsONLINE und SurgeryONLINE kuratiert MED-EL zwei Vortragsreihen mit regelm\u00e4\u00dfigen Pr\u00e4sentationen interner und externer H\u00f6rexpert*innen. Kommende Veranstaltungen dieser beiden Reihen finden Sie auf <a href=\"http:\/\/www.medel.pro\/events\/eventsonline\" target=\"_blank\" rel=\"noopener\">www.medel.pro\/events\/eventsonline<\/a>. Um keinen Live-Vortrag zu verpassen, empfehlen wir Ihnen, den <u><a href=\"https:\/\/www.medel.pro\/events\/eventsonline#RegisterEvent\" target=\"_blank\" rel=\"noopener\">EventsONLINE Newsletter zu abonnieren<\/a><\/u>. So erhalten Sie vor jeder Veranstaltung zeitgerecht eine Einladung.<\/p>\n<p>ExpertsONLINE sowie SurgeryONLINE Veranstaltungen umfassen \u00fcblicherweise einen Fachvortrag und\/oder ein Expertengespr\u00e4ch mit einer anschlie\u00dfenden Diskussion, in deren Rahmen das Online-Publikum die M\u00f6glichkeit bekommt, sich interaktiv zu beteiligen und Fragen zu stellen.<\/p>\n<p><u><a href=\"https:\/\/academy.medel.com\/course\/view.php?id=710\" target=\"_blank\" rel=\"noopener\">Aufzeichnungen vergangener Vortr\u00e4ge finden Sie in der MED-EL Akademie<\/a><\/u> (einloggen und erneut auf den Link klicken) und auf dem <u><a href=\"https:\/\/www.youtube.com\/channel\/UCKeXj4XUAG4QgszCH9m874g\/videos?app=desktop\" target=\"_blank\" rel=\"noopener\">YouTube Fachleute-Kanal von MED-EL<\/a><\/u> (ohne Login).<\/p>\n<div style=\"background-color: #f0f0f0; padding: 10px 15px; border: 1px solid #ccc; float: left;\"><em><a href=\"https:\/\/my.medel.com\/de\/register\/professional\" target=\"_blank\" rel=\"noopener\">&gt;<\/a><em><a href=\"https:\/\/www.medel.pro\/events\/eventsonline#RegisterEvent\" target=\"_blank\" rel=\"noopener\">&gt; EventsONLINE Newsletter abonnieren<\/a><\/em><\/em><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Podcasts von MED-EL<\/strong><\/h3>\n<p>Wenn Sie gern Podcasts h\u00f6ren, zum Beispiel beim Laufen, Zugfahren oder im Auto, m\u00f6chten wir Ihnen die <u><a href=\"https:\/\/medel.libsyn.com\/\" target=\"_blank\" rel=\"noopener\">MED-EL Podcast-Sammlung<\/a><\/u> ans Herz legen. Die Podcasts dauern im Schnitt zwischen 10 und 30 Minuten. Dahinter steckt die Idee, spannende Inhalte in unterhaltsamer und leicht verdaulicher Form zu vermitteln. Die Themen sind ebenso vielf\u00e4ltige wie die G\u00e4ste, welche die Podcasts einsprechen.<\/p>\n<p>Renommierte Chirurg*innen kl\u00e4ren \u00fcber unterschiedliche CI-Elektroden auf, Nutzer*innen erz\u00e4hlen, wie ihnen das Implantat zu einem neuen Lebensgef\u00fchl verholfen hat, und Reha-Expert*innen erl\u00e4utern die Bedeutung des H\u00f6rtrainings f\u00fcr einseitig ertaubte Menschen.<\/p>\n<p>Monat f\u00fcr Monat kommen neue Episoden hinzu \u2013 zu jeder einzelnen gibt es ein PDF-Transkript zum Herunterladen. Die Podcasts sind in englischer Sprache und behandeln ganz unterschiedliche Themengebiete: Produkte (ADHEAR, BONEBRIDGE, RONDO 3, OTOPLAN, \u2026) genauso wie die Themenfelder <em>tonotope Stimulation in der Cochlea<\/em>, <em>audiologische Anpassung<\/em>, <em>MRTs mit Cochlea-Implantaten<\/em> oder <em>Rehabilitation nach der Implantation<\/em>.<\/p>\n<h3><strong>medel.pro<\/strong><\/h3>\n<p>Komplett frei zug\u00e4nglich ist auch die speziell auf die Bed\u00fcrfnisse und Interessen von medizinischem Fachpersonal ausgerichtete Webseite <a href=\"http:\/\/www.medel.pro\">www.medel.pro<\/a>.<\/p>\n<p>Einige wichtige Inhalte:<\/p>\n<ul>\n<li>\u00dcberblick \u00fcber alle <u><a href=\"https:\/\/www.medel.pro\/indications\" target=\"_blank\" rel=\"noopener\">MED-EL Produktindikationen mit Candidate Selection Tool<\/a><\/u> zur Unterst\u00fctzung bei der Auswahl der geeigneten H\u00f6rl\u00f6sung<\/li>\n<li>Detaillierte Produktinfos zu Cochlea-, Mittelohr- und Knochenleitungsimplantaten<\/li>\n<li><u><a href=\"https:\/\/www.medel.pro\/events\" target=\"_blank\" rel=\"noopener\">Veranstaltungshinweise<\/a><\/u><\/li>\n<li>Downloads: <u><a href=\"https:\/\/www.medel.pro\/online-resources\/white-papers\" target=\"_blank\" rel=\"noopener\">White Papers<\/a><\/u>, <u><a href=\"https:\/\/www.medel.pro\/online-resources\/bibliography\" target=\"_blank\" rel=\"noopener\">Fachbibliografien<\/a><\/u>, <a href=\"https:\/\/www.medel.pro\/online-resources\/timing-settings-for-hearing-aids\" target=\"_blank\" rel=\"noopener\"><u>Liste mit exakten Angaben zur Zeitverz\u00f6gerung von H\u00f6rger\u00e4ten zur bimodalen Synchronisation<\/u><\/a>\u00a0u.v.m.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>Noch mehr entdecken<\/h4>\n<p>Legen Sie gleich los \u2013 holen Sie sich Ihren individuell abgestimmten, kostenlosen myMED-EL Account, st\u00f6bern sie in unseren Plattformen und Online-Kan\u00e4len, sehen Sie sich aufregende OP-Videos an und h\u00f6ren Sie in die MED-EL Podcasts rein.<\/p>\n<p>Und vergessen Sie nicht, den <u><a href=\"https:\/\/blog.medel.pro\/de\/abonnieren\/\" target=\"_blank\" rel=\"noopener\">MED-EL Professionals Blog zu abonnieren<\/a><\/u>. So erhalten Sie regelm\u00e4\u00dfige Updates zu neuen Produkten, Tipps und Tricks f\u00fcr Ihre t\u00e4gliche Praxis sowie Fallstudien aus aller Welt direkt in Ihren E-Mail-Posteingang.<\/p>\n<div style=\"background-color: #f0f0f0; padding: 10px 15px; border: 1px solid #ccc; float: left;\"><em><em><a href=\"https:\/\/blog.medel.pro\/de\/abonnieren\/\" target=\"_blank\" rel=\"noopener\">&gt;&gt; Professionals Blog Newsletter abonnieren<\/a><\/em><\/em><\/div>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Blogs, Video-Bibliotheken, Online-Seminare, Podcasts: Das MED-EL Universum bietet etliche Plattformen mit wertvollen Informationen, Downloads und Materialien f\u00fcr Fachleute \u2013 ganz egal, ob Sie in der HNO-Chirurgie, in der Audiologie oder in der Rehabilitation arbeiten. Bei diesem vielf\u00e4ltigen Angebot kann man aber schon einmal den \u00dcberblick verlieren. Damit Sie auch wirklich das finden, was f\u00fcr Sie [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":24192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2150,2148,2149,2798],"tags":[2217,2360,2361,2574,2362,2363,2364,2365,2366,2367,2368,2369,2370,2371,2372,2373,2374,2375,2376,2377,2378,2576],"class_list":["post-25723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audiologie","category-chirurgie","category-produkte-neuheiten","category-rehabilitation-de","tag-audiologe","tag-downloads-fuer-fachleute","tag-downloads-fuer-hoer-experten","tag-expertsonline-de","tag-fachinformation-hoeren","tag-hno-aerzte","tag-hno-medizin","tag-hoerspezialist","tag-infos-fuer-hoerexperten","tag-materialien-fuer-hoerexperten","tag-med-el-akademie","tag-med-el-e-learning","tag-med-el-fachleute","tag-med-el-kurse","tag-med-el-podcasts","tag-med-el-webinare","tag-mymed-el","tag-op-videos","tag-otolaryngologie","tag-plattformen-zum-thema-hoeren","tag-ressourcen-fuer-hoerspezialisten","tag-surgeryonline-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog<\/title>\n<meta name=\"description\" content=\"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog\" \/>\n<meta property=\"og:description\" content=\"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\" \/>\n<meta property=\"og:site_name\" content=\"MED-EL Professionals Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-23T12:57:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-23T16:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@medel\" \/>\n<meta name=\"twitter:site\" content=\"@medel\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02\"},\"headline\":\"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden\",\"datePublished\":\"2023-02-23T12:57:25+00:00\",\"dateModified\":\"2024-01-23T16:25:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\"},\"wordCount\":842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\"},\"image\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg\",\"keywords\":[\"Audiologe\",\"Downloads f\u00fcr Fachleute\",\"Downloads f\u00fcr H\u00f6r-Experten\",\"ExpertsONLINE\",\"Fachinformation H\u00f6ren\",\"HNO-\u00c4rzte\",\"HNO-Medizin\",\"H\u00f6rspezialist\",\"Infos f\u00fcr H\u00f6rexperten\",\"Materialien f\u00fcr H\u00f6rexperten\",\"MED-EL Akademie\",\"MED-EL e-learning\",\"MED-EL Fachleute\",\"MED-EL Kurse\",\"MED-EL Podcasts\",\"MED-EL Webinare\",\"myMED-EL\",\"OP-Videos\",\"Otolaryngologie\",\"Plattformen zum Thema H\u00f6ren\",\"Ressourcen f\u00fcr H\u00f6rspezialisten\",\"SurgeryONLINE\"],\"articleSection\":[\"Audiologie\",\"Chirurgie\",\"Produkte und Neuheiten\",\"Rehabilitation\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\",\"url\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\",\"name\":\"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg\",\"datePublished\":\"2023-02-23T12:57:25+00:00\",\"dateModified\":\"2024-01-23T16:25:49+00:00\",\"description\":\"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.\",\"breadcrumb\":{\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg\",\"width\":800,\"height\":400,\"caption\":\"Plattformen und Materialien f\u00fcr Fachleute\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.medel.pro\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#website\",\"url\":\"https:\/\/blog.medel.pro\/de\/\",\"name\":\"MED-EL Professionals Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.medel.pro\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#organization\",\"name\":\"MED-EL Professionals Blog\",\"url\":\"https:\/\/blog.medel.pro\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"contentUrl\":\"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg\",\"width\":200,\"height\":200,\"caption\":\"MED-EL Professionals Blog\"},\"image\":{\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/medel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02\",\"name\":\"MED-EL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog","description":"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/","og_locale":"de_DE","og_type":"article","og_title":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog","og_description":"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.","og_url":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/","og_site_name":"MED-EL Professionals Blog","article_published_time":"2023-02-23T12:57:25+00:00","article_modified_time":"2024-01-23T16:25:49+00:00","og_image":[{"width":800,"height":400,"url":"http:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_creator":"@medel","twitter_site":"@medel","twitter_misc":{"Verfasst von":"MED-EL","Gesch\u00e4tzte Lesezeit":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#article","isPartOf":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02"},"headline":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden","datePublished":"2023-02-23T12:57:25+00:00","dateModified":"2024-01-23T16:25:49+00:00","mainEntityOfPage":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/"},"wordCount":842,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.pro\/de\/#organization"},"image":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg","keywords":["Audiologe","Downloads f\u00fcr Fachleute","Downloads f\u00fcr H\u00f6r-Experten","ExpertsONLINE","Fachinformation H\u00f6ren","HNO-\u00c4rzte","HNO-Medizin","H\u00f6rspezialist","Infos f\u00fcr H\u00f6rexperten","Materialien f\u00fcr H\u00f6rexperten","MED-EL Akademie","MED-EL e-learning","MED-EL Fachleute","MED-EL Kurse","MED-EL Podcasts","MED-EL Webinare","myMED-EL","OP-Videos","Otolaryngologie","Plattformen zum Thema H\u00f6ren","Ressourcen f\u00fcr H\u00f6rspezialisten","SurgeryONLINE"],"articleSection":["Audiologie","Chirurgie","Produkte und Neuheiten","Rehabilitation"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/","url":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/","name":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden - MED-EL Professionals Blog","isPartOf":{"@id":"https:\/\/blog.medel.pro\/de\/#website"},"primaryImageOfPage":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage"},"image":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg","datePublished":"2023-02-23T12:57:25+00:00","dateModified":"2024-01-23T16:25:49+00:00","description":"myMED-EL, MED-EL Akademie, Surgical Video Library, Podcasts: Online-Plattformen von MED-EL bieten Downloads und Materialien f\u00fcr Fachleute.","breadcrumb":{"@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#primaryimage","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/02\/smb_hq-en_post-educational-resources-for-hearing-professionals-1.jpg","width":800,"height":400,"caption":"Plattformen und Materialien f\u00fcr Fachleute"},{"@type":"BreadcrumbList","@id":"http:\/\/blog.medel.pro\/de\/produkte-neuheiten\/plattformen-und-materialien-fuer-fachleute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.pro\/de\/"},{"@type":"ListItem","position":2,"name":"Plattformen und Materialien f\u00fcr Fachleute: Wo Sie was finden"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.pro\/de\/#website","url":"https:\/\/blog.medel.pro\/de\/","name":"MED-EL Professionals Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.pro\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.pro\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/blog.medel.pro\/de\/#organization","name":"MED-EL Professionals Blog","url":"https:\/\/blog.medel.pro\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","contentUrl":"https:\/\/blog.medel.pro\/wp-content\/uploads\/2023\/05\/MED-EL_RGB_Red_Symbol.jpg","width":200,"height":200,"caption":"MED-EL Professionals Blog"},"image":{"@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/medel"]},{"@type":"Person","@id":"https:\/\/blog.medel.pro\/de\/#\/schema\/person\/b81eab3e22287063f6f0d9e2499d0f02","name":"MED-EL"}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/posts\/25723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/comments?post=25723"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/posts\/25723\/revisions"}],"predecessor-version":[{"id":26380,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/posts\/25723\/revisions\/26380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/media\/24192"}],"wp:attachment":[{"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/media?parent=25723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/categories?post=25723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.pro\/de\/wp-json\/wp\/v2\/tags?post=25723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}